{"id":25299,"date":"2022-07-15T01:44:01","date_gmt":"2022-07-15T01:44:01","guid":{"rendered":"https:\/\/www.cos.net.au\/c\/?page_id=25299"},"modified":"2024-02-05T05:05:33","modified_gmt":"2024-02-05T05:05:33","slug":"fallback","status":"publish","type":"page","link":"https:\/\/www.cos.net.au\/c\/","title":{"rendered":"Fallback"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25299\" class=\"elementor elementor-25299\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-684ada2 e-flex e-con-boxed e-con e-parent\" data-id=\"684ada2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a2dec05 e-con-full e-flex e-con e-child\" data-id=\"a2dec05\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4d3225 elementor-posts__hover-none elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"e4d3225\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;pagination_type&quot;:&quot;numbers&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-57404 post type-post status-publish format-standard has-post-thumbnail hentry category-cospedia tag-asset-write-off tag-tax-claims tag-tax-deductions tag-tax-write-off\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.cos.net.au\/c\/cospedia\/australias-instant-asset-write-off\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"246\" src=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/05\/asset-write-off-300x246.jpg.avif\" class=\"attachment-medium size-medium wp-image-57405\" alt=\"asset write-off for tax deductions\" srcset=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/05\/asset-write-off-300x246.jpg.avif 300w, https:\/\/www.cos.net.au\/c\/wp-content\/uploads\/2026\/05\/asset-write-off.jpg 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-smush-avif-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/asset-write-off-300x246.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/asset-write-off-300x246.jpg 300w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/asset-write-off.jpg 768w&quot;}\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.cos.net.au\/c\/cospedia\/australias-instant-asset-write-off\" >\n\t\t\t\tMake the Most of Australia&#8217;s $20,000 Instant Asset Write-Off\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Australia&#8217;s $20,000 asset write-off offers small businesses an opportunity to boost cashflow. Find out which assets are eligible to maximise your claim!<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMay 10, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-57360 post type-post status-publish format-standard has-post-thumbnail hentry category-cospedia category-social-responsibility tag-food-waste tag-office-composting\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.cos.net.au\/c\/cospedia\/office-composting\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"246\" src=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/office-composting-300x246.jpg.avif\" class=\"attachment-medium size-medium wp-image-57362\" alt=\"office composting\" srcset=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/office-composting-300x246.jpg.avif 300w, https:\/\/www.cos.net.au\/c\/wp-content\/uploads\/2026\/04\/office-composting.jpg 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-smush-avif-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/office-composting-300x246.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/office-composting-300x246.jpg 300w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/office-composting.jpg 768w&quot;}\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.cos.net.au\/c\/cospedia\/office-composting\" >\n\t\t\t\tZero Waste in the Breakroom: How to Set Up Office Composting That Actually Works\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Organic waste makes up a significant portion of what Australian workplaces throw away. Here&#8217;s how to set up an office composting system that works.<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 29, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-57352 post type-post status-publish format-standard has-post-thumbnail hentry category-cospedia category-education category-social-responsibility tag-composting tag-food-waste tag-school-composting-programs\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.cos.net.au\/c\/cospedia\/school-composting-programs\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"246\" src=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/school-composting-programs-300x246.jpg.avif\" class=\"attachment-medium size-medium wp-image-57353\" alt=\"school composting programs\" srcset=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/school-composting-programs-300x246.jpg.avif 300w, https:\/\/www.cos.net.au\/c\/wp-content\/uploads\/2026\/04\/school-composting-programs.jpg 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-smush-avif-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/school-composting-programs-300x246.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/school-composting-programs-300x246.jpg 300w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/school-composting-programs.jpg 768w&quot;}\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.cos.net.au\/c\/cospedia\/school-composting-programs\" >\n\t\t\t\tSchool Composting Programs: Turning Food Waste into Learning Opportunities\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>School composting programs are powerful opportunities to reduce waste, save money, and create hands-on learning experiences. <\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 28, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-57262 post type-post status-publish format-standard has-post-thumbnail hentry category-cospedia category-productivity tag-classroomdeclutter tag-clutter tag-deskorganisation tag-getorganisedday tag-officeorganisation tag-officestorage tag-organisation-3\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.cos.net.au\/c\/cospedia\/get-organised-day-declutter-checklist\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"164\" src=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Gemini_Generated_Image_xjn0p9xjn0p9xjn0-300x164.png.avif\" class=\"attachment-medium size-medium wp-image-57306\" alt=\"Tips for office and classroom Desk organisation\" srcset=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Gemini_Generated_Image_xjn0p9xjn0p9xjn0-300x164.png.avif 300w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Gemini_Generated_Image_xjn0p9xjn0p9xjn0-1024x559.png.avif 1024w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Gemini_Generated_Image_xjn0p9xjn0p9xjn0-768x419.png.avif 768w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Gemini_Generated_Image_xjn0p9xjn0p9xjn0-1080x589.png.avif 1080w, https:\/\/www.cos.net.au\/c\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_xjn0p9xjn0p9xjn0.png 1408w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-smush-avif-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Gemini_Generated_Image_xjn0p9xjn0p9xjn0-300x164.png&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Gemini_Generated_Image_xjn0p9xjn0p9xjn0-300x164.png 300w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Gemini_Generated_Image_xjn0p9xjn0p9xjn0-1024x559.png 1024w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Gemini_Generated_Image_xjn0p9xjn0p9xjn0-768x419.png 768w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Gemini_Generated_Image_xjn0p9xjn0p9xjn0-1080x589.png 1080w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Gemini_Generated_Image_xjn0p9xjn0p9xjn0.png 1408w&quot;}\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.cos.net.au\/c\/cospedia\/get-organised-day-declutter-checklist\" >\n\t\t\t\tGet Organised Day: The Ultimate Desk &amp; Classroom Declutter Checklist\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Productivity\u00a0doesn\u2019t\u00a0start when you open your laptop or walk into a classroom, it starts the moment you step into your space.\u00a0A<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 23, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-56961 post type-post status-publish format-standard has-post-thumbnail hentry category-cospedia category-education tag-craft-worksheet tag-diy-worksheet tag-printable-worksheet tag-teacher-appreciation-week tag-teachers-day tag-worksheet tag-worksheet-for-kids\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.cos.net.au\/c\/cospedia\/teacher-appreciation-week-worksheets\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"247\" src=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Teacher-Appreciation-Week-Worksheets--300x247.png.avif\" class=\"attachment-medium size-medium wp-image-57068\" alt=\"Teacher Appreciation Week - Worksheets for Kids\" srcset=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Teacher-Appreciation-Week-Worksheets--300x247.png.avif 300w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Teacher-Appreciation-Week-Worksheets--1024x842.png.avif 1024w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Teacher-Appreciation-Week-Worksheets--768x631.png.avif 768w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Teacher-Appreciation-Week-Worksheets--1536x1262.png.avif 1536w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Teacher-Appreciation-Week-Worksheets--1080x888.png.avif 1080w, https:\/\/www.cos.net.au\/c\/wp-content\/uploads\/2026\/04\/Teacher-Appreciation-Week-Worksheets-.png 1825w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-smush-avif-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Teacher-Appreciation-Week-Worksheets--300x247.png&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Teacher-Appreciation-Week-Worksheets--300x247.png 300w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Teacher-Appreciation-Week-Worksheets--1024x842.png 1024w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Teacher-Appreciation-Week-Worksheets--768x631.png 768w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Teacher-Appreciation-Week-Worksheets--1536x1262.png 1536w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Teacher-Appreciation-Week-Worksheets--1080x888.png 1080w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Teacher-Appreciation-Week-Worksheets-.png 1825w&quot;}\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.cos.net.au\/c\/cospedia\/teacher-appreciation-week-worksheets\" >\n\t\t\t\tTeacher Appreciation Week: Engaging Printable Worksheets for Kids\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Teacher Appreciation Week is a special time to recognise the incredible impact teachers have on our lives. Their patience, encouragement,<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 22, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-56978 post type-post status-publish format-standard has-post-thumbnail hentry category-cospedia category-education tag-celebrate-mothers-day tag-diy-art-and-craft-projects tag-gift-for-mum tag-mothers-day-craft tag-mothers-day-gift tag-mothers-day tag-mum\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.cos.net.au\/c\/cospedia\/5-mothers-day-craft-for-kids\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"247\" src=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Mothers-Day-Craft-300x247.png.avif\" class=\"attachment-medium size-medium wp-image-57211\" alt=\"5 Mother&#039;s Day Craft for Kids\" srcset=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Mothers-Day-Craft-300x247.png.avif 300w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Mothers-Day-Craft-1024x842.png.avif 1024w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Mothers-Day-Craft-768x631.png.avif 768w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Mothers-Day-Craft-1536x1262.png.avif 1536w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Mothers-Day-Craft-1080x888.png.avif 1080w, https:\/\/www.cos.net.au\/c\/wp-content\/uploads\/2026\/04\/Mothers-Day-Craft.png 1825w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-smush-avif-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Mothers-Day-Craft-300x247.png&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Mothers-Day-Craft-300x247.png 300w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Mothers-Day-Craft-1024x842.png 1024w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Mothers-Day-Craft-768x631.png 768w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Mothers-Day-Craft-1536x1262.png 1536w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Mothers-Day-Craft-1080x888.png 1080w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Mothers-Day-Craft.png 1825w&quot;}\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.cos.net.au\/c\/cospedia\/5-mothers-day-craft-for-kids\" >\n\t\t\t\t5 Easy and Heartfelt Mother\u2019s Day Craft Ideas for Kids\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Mother\u2019s Day is the perfect opportunity to help kids create something heartfelt, personal, and full of love. While store-bought gifts<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 20, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-57087 post type-post status-publish format-standard has-post-thumbnail hentry category-cospedia category-health-wellbeing tag-health-and-wellness tag-productivity tag-top tag-womens-wellbeing\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.cos.net.au\/c\/cospedia\/womens-wellbeing\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"246\" src=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/womens-wellbeing-300x246.jpg.avif\" class=\"attachment-medium size-medium wp-image-57088\" alt=\"women&#039;s wellbeing at work\" srcset=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/womens-wellbeing-300x246.jpg.avif 300w, https:\/\/www.cos.net.au\/c\/wp-content\/uploads\/2026\/04\/womens-wellbeing.jpg 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-smush-avif-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/womens-wellbeing-300x246.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/womens-wellbeing-300x246.jpg 300w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/womens-wellbeing.jpg 768w&quot;}\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.cos.net.au\/c\/cospedia\/womens-wellbeing\" >\n\t\t\t\tPut Yourself First: Supporting Women&#8217;s Wellbeing at Work\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Women&#8217;s wellbeing at work is about creating environments where women feel physically, mentally, and socially comfortable every day. <\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 17, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-57006 post type-post status-publish format-standard has-post-thumbnail hentry category-cospedia category-social-responsibility tag-earth-day tag-earth-day-2026 tag-eco-consciousness tag-eco-friendly-products tag-sustainability\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.cos.net.au\/c\/cospedia\/earth-day-2026\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"246\" src=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/earth-day-2026-300x246.jpg.avif\" class=\"attachment-medium size-medium wp-image-57007\" alt=\"earth day 2026\" srcset=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/earth-day-2026-300x246.jpg.avif 300w, https:\/\/www.cos.net.au\/c\/wp-content\/uploads\/2026\/04\/earth-day-2026.jpg 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-smush-avif-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/earth-day-2026-300x246.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/earth-day-2026-300x246.jpg 300w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/earth-day-2026.jpg 768w&quot;}\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.cos.net.au\/c\/cospedia\/earth-day-2026\" >\n\t\t\t\tEarth Day 2026: How Australian Workplaces &amp; Schools Can Lead on Sustainability\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Earth Day 2026 presents an opportunity to turn sustainable intentions into habits that last.<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 15, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-56814 post type-post status-publish format-standard has-post-thumbnail hentry category-cospedia category-education tag-art-activity tag-craft-worksheet tag-earth-day tag-earth-day-2026 tag-top tag-worksheet tag-worksheet-for-kids\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.cos.net.au\/c\/cospedia\/earth-day-eco-friendly-worksheets\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"247\" src=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Earth-Day-Worksheet-2026-300x247.png.avif\" class=\"attachment-medium size-medium wp-image-56917\" alt=\"Earth Day worksheet for kids\" srcset=\"https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Earth-Day-Worksheet-2026-300x247.png.avif 300w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Earth-Day-Worksheet-2026-1024x842.png.avif 1024w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Earth-Day-Worksheet-2026-768x631.png.avif 768w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Earth-Day-Worksheet-2026-1536x1262.png.avif 1536w, https:\/\/www.cos.net.au\/c\/wp-content\/smush-avif\/2026\/04\/Earth-Day-Worksheet-2026-1080x888.png.avif 1080w, https:\/\/www.cos.net.au\/c\/wp-content\/uploads\/2026\/04\/Earth-Day-Worksheet-2026.png 1825w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-smush-avif-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Earth-Day-Worksheet-2026-300x247.png&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Earth-Day-Worksheet-2026-300x247.png 300w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Earth-Day-Worksheet-2026-1024x842.png 1024w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Earth-Day-Worksheet-2026-768x631.png 768w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Earth-Day-Worksheet-2026-1536x1262.png 1536w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Earth-Day-Worksheet-2026-1080x888.png 1080w, https:\\\/\\\/www.cos.net.au\\\/c\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Earth-Day-Worksheet-2026.png 1825w&quot;}\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.cos.net.au\/c\/cospedia\/earth-day-eco-friendly-worksheets\" >\n\t\t\t\tEarth Day Worksheets to Inspire Eco-Friendly Habits\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Earth Day is a wonderful opportunity to help children understand the importance of caring for our planet while building essential<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 9, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"65\" data-next-page=\"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/pages\/25299\/page\/2\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Pagination\">\n\t\t\t<span aria-current=\"page\" class=\"page-numbers current\"><span class=\"elementor-screen-only\">Page<\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/pages\/25299\/page\/2\"><span class=\"elementor-screen-only\">Page<\/span>2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/pages\/25299\/page\/3\"><span class=\"elementor-screen-only\">Page<\/span>3<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/pages\/25299\/page\/4\"><span class=\"elementor-screen-only\">Page<\/span>4<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/pages\/25299\/page\/5\"><span class=\"elementor-screen-only\">Page<\/span>5<\/a>\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class='watch-action'><div class='watch-position align-left'><div class='action-like'><a class='lbg-style3 like-56814 jlk' href='javascript:void(0)' data-task='like' data-post_id='56814' data-nonce='ccd7527625' rel='nofollow'><img class='wti-pixel' src='https:\/\/www.cos.net.au\/c\/wp-content\/plugins\/wti-like-post\/images\/pixel.gif' title='Did you find this useful?' \/><span class='lc-56814 lc'>0<\/span><\/a><\/div><div class='action-unlike'><a class='unlbg-style3 unlike-56814 jlk' href='javascript:void(0)' data-task='unlike' data-post_id='56814' data-nonce='ccd7527625' rel='nofollow'><img class='wti-pixel' src='https:\/\/www.cos.net.au\/c\/wp-content\/plugins\/wti-like-post\/images\/pixel.gif' title='' \/><span class='unlc-56814 unlc'>0<\/span><\/a><\/div> <\/div> <div class='status-56814 status align-left'><\/div><\/div><div class='wti-clear'><\/div>","protected":false},"excerpt":{"rendered":"<p>0 0<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25299","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/pages\/25299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/comments?post=25299"}],"version-history":[{"count":7,"href":"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/pages\/25299\/revisions"}],"predecessor-version":[{"id":37577,"href":"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/pages\/25299\/revisions\/37577"}],"wp:attachment":[{"href":"https:\/\/www.cos.net.au\/c\/wp-json\/wp\/v2\/media?parent=25299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}